{"id":4687,"date":"2018-01-18T20:16:28","date_gmt":"2018-01-18T20:16:28","guid":{"rendered":"https:\/\/how-to.watch\/connecter-tv-sony-vpn\/"},"modified":"2018-01-18T20:16:28","modified_gmt":"2018-01-18T20:16:28","slug":"connecter-tv-sony-vpn","status":"publish","type":"post","link":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/","title":{"rendered":"Connecter votre TV Connect\u00e9e Sony \u00e0 un VPN"},"content":{"rendered":"<p>Au cours des ann\u00e9es, Sony s&#8217;est impos\u00e9 comme le leader de la technologie t\u00e9l\u00e9visuelle. Et aujourd&#8217;hui encore plus que jamais, les t\u00e9l\u00e9visions connect\u00e9es Sony offrent une polyvalence et un plaisir \u00e0 l&#8217;utilisation in\u00e9gal\u00e9s pour l&#8217;utilisateur. Sony parvient \u00e0 repousser de mani\u00e8re constante les fronti\u00e8res de la technologie. De la HD tr\u00e8s haute qualit\u00e9 et la 4K jusqu&#8217;aux TV OLED, les utilisateurs se retrouvent l&#8217;embarras du choix lorsqu&#8217;ils d\u00e9cident d\u2019acqu\u00e9rir une t\u00e9l\u00e9vision Sony.<\/p>\n<p>Les t\u00e9l\u00e9visions connect\u00e9es Sony sont livr\u00e9es cl\u00e9s-en-main et avec tout un lot d&#8217;applications pour le streaming, et c&#8217;est sans compter toutes les possibilit\u00e9s pour l&#8217;utilisateur de t\u00e9l\u00e9charger \u00e9galement des applications tierces. Cependant, \u00eatre connect\u00e9 et avoir \u00e0 disposition de nombreuses plateformes de streaming a aussi un revers de m\u00e9daille : il est possible que vous ne puissiez pas acc\u00e9der \u00e0 tous les contenus que vous voulez car ils peuvent potentiellement \u00eatre bloqu\u00e9s dans votre r\u00e9gion. C&#8217;est ce que l&#8217;on appelle le <a href=\"https:\/\/how-to.watch\/fr\/quest-ce-que-le-geoblocking\/\">geoblocking<\/a> et c&#8217;est beaucoup plus r\u00e9pandu que vous le pensez au premier abord.<\/p>\n<p>Les t\u00e9l\u00e9-diffuseurs bloquent r\u00e9guli\u00e8rement l&#8217;acc\u00e8s \u00e0 leurs contenus en fonction de la localisation des utilisateurs. Ce qui veut dire que par exemple, au Canada, vous n&#8217;aurez pas acc\u00e8s aux m\u00eames programmes qu&#8217;en Europe. La bonne nouvelle, c&#8217;est que l&#8217;on peut contourner ces restrictions. Il suffit d&#8217;utiliser un VPN &#8211; Virtual Private Network ou R\u00e9seau Priv\u00e9 Virtuel.<\/p>\n<p>Le VPN propos\u00e9 par la compagnie Shellfire est une solution tout-en-un pour s&#8217;affranchir du geoblocking. Le service est disponible sur toutes les plateforme, application incluse. Comme les autres VPN, Shellfire permet de contourner les g\u00e9orestrictions qui affectent les plateformes de streaming ou les applications de musique.<\/p>\n<p class=\"p1\"><span class=\"s1\">L&#8217;application permet \u00e0 l&#8217;utilisateur de choisir le pays depuis lequel il souhaite se connecter. Via la version gratuite de Shellfire, vous pourrez vous connecter depuis 2 pays seulement. Le pack Premier Prix permet de se connecter depuis une douzaine de pays, tandis que le pack Premium ont acc\u00e8s aux meilleurs serveurs distants pour se connecter. C&#8217;est important de s&#8217;en souvenir, car les t\u00e9l\u00e9vision Sony exploitant le syst\u00e8me Android, elles ont acc\u00e8s au Google Play Store, et les utilisateurs peuvent donc tr\u00e8s facilement t\u00e9l\u00e9charger l&#8217;application Shellfire gratuitement.\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4586\" src=\"https:\/\/how-to.watch\/edirewhu\/2018\/01\/image1-1.jpg\" alt=\"Sony Smart TV Network Setting\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/how-to.watch\/edirewhu\/2018\/01\/image1-1.jpg 1920w, https:\/\/how-to.watch\/edirewhu\/2018\/01\/image1-1-300x169.jpg 300w, https:\/\/how-to.watch\/edirewhu\/2018\/01\/image1-1-768x432.jpg 768w, https:\/\/how-to.watch\/edirewhu\/2018\/01\/image1-1-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/span><\/p>\n<h2 class=\"p4\"><span class=\"s1\"><b>Connecter votre TV Sony \u00e0 Internet<\/b><\/span><\/h2>\n<p>Comme beaucoup d&#8217;autres appareils, votre t\u00e9l\u00e9vision connect\u00e9e fonctionnera de mani\u00e8re optimale une fois connect\u00e9e \u00e0 Internet. Voici quelques instructions que vous pouvez suivre pour vous assurer que votre TV Sony est bien correctement connect\u00e9.<\/p>\n<h2 class=\"p1\"><span class=\"s1\"><b>Connecter la TV Sony Android \u00e0 Internet en Ethernet<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Les mod\u00e8les suivant tournent sous Android et poss\u00e8dent une connexion Ethernet :<\/span><\/p>\n<blockquote><p><span class=\"s1\"><i>KD75XE85, KD65XE85, KD55XE85, KD55XE80, KD49XE80, KD43XE80, KDL-49WE75, KDL-40WE75, KDL-49WE755, KDL-40WE755, KDL-43WE755, KD49WE66, KD40WE66, KD32WE61, KD40RE4, KD32RE4, XBR55A1E, XBR65A1E, XBR77A1E. XBR-49X800E, XBR-43X800E, XBR-55X850E, XBR-65X850E, XBR-77X850E, XBR-49X900E, XBR-55X900E, XBR-65X900E, XBR-75X900E, XBR55X930E, XBR65X900E, XBR-75Z9D, XBR-85X850D, XBR-55A1E, XBR-65A1E, XBR-77A1E, KD-43X720E, KD-49X720E, KD-50X690E, KD-55X720E, KD-60X690E, KD-70X690E, XBR-43X800E, XBR-49X800E, XBR-49X900E, XBR-55X800E, XBR-55X900E, XBR-55X930E, XBR-65X850E, XBR-65X900E, XBR-65X930E, XBR-75X850E, XBR-75X900E, KDL-48W650D, KDL-55W650D, XBR-100Z9D, XBR-43X800D, XBR-49X700D, XBR-49X800D, XBR-55X700D, XBR-55X850D, XBR-55X930D, XBR-65X750D, XBR-65X850D, XBR-65X930D, XBR-65Z9D, XBR-75X850D, XBR-75X940D, XBR-55X930D, XBR-55X930D, XBR-75X940D, XBR55X850D, XBR65X850D, XBR75X850D, XBR85X850D, KD-43X800D, KD-49X800D, KD-65X930D, KD-55X930D, KD-55X930D, KD-75X940D, KD55X850D, KD65X850D, KD75X850D, KD85X850D, XBR75X940C, XBR-65X930C, XBR-75X940C, XBR43X830C, KD75X940C, KD65X930C, KD75X910C, KD65X900C, KD-55X900C, KD75X850C, KD65X850C, KD55X850C, KDL-75W850C, KDL-65W850C, KDL-55W800C, KDL-50W800C, KDL-48R510C, KDL-40R510C, XBR-65X850B, XBR-65X900B, XBR-65X950B, XBR-70X850B, XBR-79X900B, XBR-84X900, XBR-85X950B, KDL-50W800C, KDL-55W700B, KDL-55W800C, KDL-65W850C, KDL-75W850C, XBR-43X830C, XBR-49X800C, XBR-49X830C, XBR-55X810C, XBR-55X850C, XBR-55X900C, XBR-65X810C, XBR-65X850C, XBR-65X900C, KDL-50R550A<\/i><\/span><\/p><\/blockquote>\n<p class=\"p1\"><span class=\"s1\">Si vous souhaitez connecter votre TV Sony par c\u00e2ble Ethernet \u00e0 Internet, voici les \u00e9tapes \u00e0 suivre :<\/span><\/p>\n<ol>\n<li class=\"p1\"><span class=\"s1\">Branchez votre c\u00e2ble Ethernet au port LAN qui se trouve \u00e0 l&#8217;arri\u00e8re de votre TV. Branchez l&#8217;autre extremit\u00e9 \u00e0 votre routeur Internet.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Appuyez sur le bouton &#8220;Menu&#8221; de votre t\u00e9l\u00e9commande.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">D\u00e9roulez les options et choisissez &#8220;Param\u00e8tres&#8221;.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Choisissez l&#8217;option &#8220;R\u00e9seau&#8221;.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">S\u00e9lectionnez &#8220;Param\u00e8tres R\u00e9seau&#8221;.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Choisissez &#8220;Connexion par c\u00e2ble&#8221; et &#8220;Auto&#8221; quand cela vous est demand\u00e9.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Enfin, appuyez sur &#8220;Sauvegarder et se connecter&#8221;.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Vous \u00eates d\u00e9sormais connect\u00e9 \u00e0 internet.<\/span><\/li>\n<\/ol>\n<h2 class=\"p1\"><span class=\"s1\"><b>Connecter la TV Sony Android \u00e0 Internet en WiFi<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Les mod\u00e8les suivant tournent sous Android et poss\u00e8dent une connexion WiFi :<br \/>\n<\/span><\/p>\n<blockquote>\n<p class=\"p5\"><span class=\"s1\"><i>KDL-65W850A, KDL-70R520A, KDL-70R550A, XBR-55X850A, XBR-55X900A, XBR-65X850A, XBR-65X900A, KDL-48W600B, KDL-50W700B, KDL-50W800B, KDL-55W800B, KDL-55W950B, KDL-60W600B, KDL-60W610B, KDL-60W630B, KDL-60W840B, KDL-60W850B, KDL-65W950B, KDL-70W830B, KDL-70W840B, KDL-70W850B, XBR-49X850B, XBR-55X800B, XBR-55X850B, KDL-46XBR3, KDL-46XBR4, KD75XE85, KD65XE85, KD55XE85, KD55XE80, KD49XE80, KD43XE80, KDL49WE75, KDL40WE75, KDL49WE755, KDL40WE755, KDL43WE755, KD49WE66, KD40WE66, KD32WE61, KD40RE4, KD32RE4, XBR55A1E, XBR65A1E, XBR77A1E, XBR-49X800E, XBR-43X800E, XBR-55X850E, XBR-65X850E, XBR-77X850E, XBR-49X900E, XBR-55X900E, XBR-65X900E, XBR-75X900E, XBR55X930E, <\/i><\/span><span class=\"s1\"><i>XBR65X900E, XBR-75Z9D, XBR-85X850D, XBR-55A1E, XBR-65A1E, XBR-77A1E, KD-43X720E, <\/i><\/span><span class=\"s1\"><i>KD-49X720E, KD-50X690E, KD-55X720E, KD-60X690E, KD-70X690E, XBR-43X800E, XBR-49X800E, XBR-49X900E, XBR-55X800E, XBR-55X900E, XBR-55X930E, XBR-65X850E, XBR-65X900E, XBR-65X930E, XBR-75X850E, XBR-75X900E, XBR75X900E, KDL-48W650D, KDL-55W650D, XBR-100Z9D, XBR-43X800D, XBR-49X700D, XBR-49X800D, XBR-55X700D, XBR-55X850D, XBR-55X930D, XBR-65X750D, XBR-65X850D, XBR-65X930D, XBR-65Z9D, XBR-75X850D, XBR-75X940D, XBR-55X930D, XBR-55X930D, XBR-75X940D, XBR55X850D, XBR65X850D, XBR75X850D, XBR85X850D, KD-43X800D, KD-49X800D, KD-65X930D, KD-55X930D, KD-55X930D, KD-75X940D, KD55X850D, KD65X850D, KD75X850D, KD85X850D, XBR75X940C, XBR-65X930C, XBR75X910C, XBR-65X900C, XBR-55X900C, XBR-65X930C, XBR-75X850C, XBR-75X910C, XBR-75X940C, XBR43X830C, KD75X940C, KD65X930C, KD75X910C, KD65X900C, KD-55X900C, KD75X850C, KD65X850C, KD55X850C, KDL-75W850C, KDL-65W850C, KDL-55W800C, KDL-50W800C, KDL-48R510C, KDL-40R510C, XBR-65X850B, XBR-65X900B, XBR-65X950B, XBR-70X850B, XBR-79X900B, XBR-84X900, XBR-85X950B, KDL-50W800C, KDL-55W700B, KDL-55W800C, KDL-65W850C, KDL-75W850C, XBR-43X830C, XBR-49X800C, XBR-49X830C, XBR-55X810C, XBR-55X850C, XBR-55X900C, XBR-65X810C, XBR-65X850C, XBR-65X900C, KDL-50R550A<\/i><\/span><\/p>\n<\/blockquote>\n<p class=\"p1\"><span class=\"s1\">Si vous souhaitez connecter votre TV Sony \u00e0 internet en WiFi, voici les \u00e9tapes \u00e0 suivre :<br \/>\n<\/span><\/p>\n<ol>\n<li class=\"p1\"><span class=\"s1\">Appuyez sur la touche &#8220;Menu&#8221; de votre t\u00e9l\u00e9commande.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Choisissez l&#8217;option &#8220;Param\u00e8tres&#8221;, puis &#8220;R\u00e9seau&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Ensuite, s\u00e9lectionnez les &#8220;param\u00e8tres R\u00e9seau&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Lorsque cela vous est demand\u00e9, s\u00e9lectionnez l&#8217;option &#8220;Connexion sans fil&#8221; et appuyez sur &#8220;Rechercher&#8221;.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Votre t\u00e9l\u00e9vision Sony va rechercher tous les r\u00e9seaux disponibles. Il vous faudra choisir votre r\u00e9seau domestique dans la liste.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Une fois s\u00e9lectionn\u00e9, saisissez votre votre cl\u00e9 WEP puis choisissez &#8220;continuer&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Ensuite, vous devrez choisir l&#8217;option &#8220;auto&#8221; lorsque vous sera demand\u00e9 comment vous souhaitez param\u00e9trer l&#8217;adresse IP de votre t\u00e9l\u00e9vision.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Choisissez &#8220;continuer&#8221; encore cette fois, n&#8217;oubliez pas de choisir aussi &#8220;Sauvegarder et se connecter&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Une fois le param\u00e9trage termin\u00e9, vous devrez cliquer sur &#8220;ok&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Votre t\u00e9l\u00e9vision est connect\u00e9e \u00e0 votre r\u00e9seau domestique.\u00a0<\/span><\/li>\n<\/ol>\n<h2 class=\"p4\"><span class=\"s1\"><b>Installer l&#8217;application VPN Shellfire sur votre TV Sony Android<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-4593\" src=\"https:\/\/how-to.watch\/edirewhu\/2018\/01\/image2.jpg\" alt=\"Sony Bravia Smart TV\" width=\"440\" height=\"337\" srcset=\"https:\/\/how-to.watch\/edirewhu\/2018\/01\/image2.jpg 640w, https:\/\/how-to.watch\/edirewhu\/2018\/01\/image2-300x230.jpg 300w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/span>Si votre t\u00e9l\u00e9vision tourne sous Android, vous pourrez t\u00e9l\u00e9charger et installer l&#8217;application <a href=\"https:\/\/www.shellfire.fr\">VPN Shellfire<\/a>. Voici les \u00e9tapes \u00e0 suivre pour la ta t\u00e9l\u00e9charger sur votre t\u00e9l\u00e9vision connect\u00e9e Sony.<\/p>\n<ol>\n<li class=\"p1\"><span class=\"s1\">Rendez-vous \u00e0 la section Android de votre TV gr\u00e2ce \u00e0 votre t\u00e9l\u00e9commande.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">S\u00e9lectionnez l&#8217;icone Google Play et recherchez l&#8217;application VPN Shellfire.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Une fois l&#8217;\u00e9cran d&#8217;information de l&#8217;appli ouvert, choisissez &#8220;Installer&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Il vous faut cliquer sur &#8220;Accepter&#8221; \u00e0 l&#8217;\u00e9cran des permissions pour que le t\u00e9l\u00e9chargement se lance.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Une fois le t\u00e9l\u00e9chargement termin\u00e9, vous pourrez choisir &#8220;Ouvrir&#8221; \u00e0 l&#8217;\u00e9cran, ou revenir \u00e0 la section Android de votre t\u00e9l\u00e9vision, o\u00f9 vous trouverez l&#8217;application VPN Shellfire que vous venez de t\u00e9l\u00e9charger.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Une fois l&#8217;application ouverte, vous pouvez vous connecter avec un compte existant ou en cr\u00e9er un nouveau si vous n&#8217;en poss\u00e9dez pas encore. Il vous suffit de suivre les indications \u00e0 l&#8217;\u00e9cran.\u00a0<\/span><\/li>\n<\/ol>\n<h2 class=\"p1\"><span class=\"s1\"><b>Connecter votre TV Sony Linux \u00e0 votre VPN<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Beaucoup de t\u00e9l\u00e9visions connect\u00e9e r\u00e9centes tournent sous Linux. Il n&#8217;y a pas d&#8217;application VPN compatible avec le syst\u00e8me d&#8217;exploitation Linux sur les TV connect\u00e9es Sony, vous devrez donc opter pour le routeur VPN.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1699 alignleft\" src=\"https:\/\/how-to.watch\/edirewhu\/2017\/11\/macbook-770x410s-4.jpg\" alt=\"Shellfire VPN routers\" width=\"442\" height=\"235\" srcset=\"https:\/\/how-to.watch\/edirewhu\/2017\/11\/macbook-770x410s-4.jpg 770w, https:\/\/how-to.watch\/edirewhu\/2017\/11\/macbook-770x410s-4-300x160.jpg 300w, https:\/\/how-to.watch\/edirewhu\/2017\/11\/macbook-770x410s-4-768x409.jpg 768w, https:\/\/how-to.watch\/edirewhu\/2017\/11\/macbook-770x410s-4-340x180.jpg 340w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/>Le <a href=\"https:\/\/www.shellfire.fr\">routeur VPN Shellfire<\/a> est une excellente solution. Abordable, achetable en ligne depuis <a href=\"https:\/\/www.amazon.fr\/Shellfire-Router-incl-PremiumPlus-Service-White\/dp\/B0183KZGCU\">Amazon<\/a> par exemple, il se sonnecte tr\u00e8s simplement \u00e0 votre routeur Internet et \u00e0 votre t\u00e9l\u00e9vision Sony que ce soit en Ethernet ou via le WiFi.<\/p>\n<p>Lors de l&#8217;achat du routeur VPN Shellfire, vous obtenez aussi un ou deux\u00a0 an(s) d&#8217;abonnement au VPN, en fonction des options choisies. Le routeur vous est livr\u00e9 pr\u00e9-configur\u00e9, ce qui rend installation encore plus simple. Vous n&#8217;aurez besoin de rien, ni mot de passe ou autre info pour le mettre en service.<\/p>\n<h2 class=\"p4\"><span class=\"s1\"><b>Configurer votre routeur Shellfire Box<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Suivez ces quelques \u00e9tapes pour une installation facile :<\/span><\/p>\n<ol>\n<li class=\"p1\"><span class=\"s1\">Utilisez le c\u00e2ble Ethernet fourni et branchez le sur votre routeur internet.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Branchez ensuite le c\u00e2ble au port WAN du routeur Shellfire.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Mettez le routeur sous tension en le branchant \u00e0 une prise mural gr\u00e2ce au c\u00e2ble USB fourni.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">La Box s&#8217;allume automatiquement<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Une fois les LED fixes, votre appareil est connect\u00e9.\u00a0<\/span><\/li>\n<\/ol>\n<h2 class=\"p1\"><span class=\"s1\"><b>Connecter votre TV Sony sous Linux \u00e0 la Shellfire Box via Ethernet\u00a0<\/b><\/span><\/h2>\n<p>Il est fortement recommand\u00e9 de connecter votre TV Sony \u00e0 la Shellfire Box en Ethernet. La connexion en Ethernet est beaucoup plus stable qu&#8217;en WiFi. De plus, votre vitesse de connexion sera sup\u00e9rieure et cela prendra donc moins de temps pour charger vos contenus.<\/p>\n<p class=\"p1\"><span class=\"s1\">Les mod\u00e8les suivants sous Linux peuvent \u00eatre connect\u00e9s en Ethernet.\u00a0<\/span><\/p>\n<blockquote>\n<p class=\"p5\"><span class=\"s1\"><i>KD100XD9, KD75XD9, KD65XD9, KD75XE940, KD65XE930, KD55XE930, KD75XE90, KD65XE90, KD55XE90, KD49XE90.<\/i><\/span><\/p>\n<\/blockquote>\n<p class=\"p1\"><span class=\"s1\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4601 alignright\" src=\"https:\/\/how-to.watch\/edirewhu\/2018\/01\/image4.jpeg\" alt=\"Network Setting\" width=\"468\" height=\"268\" srcset=\"https:\/\/how-to.watch\/edirewhu\/2018\/01\/image4.jpeg 768w, https:\/\/how-to.watch\/edirewhu\/2018\/01\/image4-300x171.jpeg 300w\" sizes=\"auto, (max-width: 468px) 100vw, 468px\" \/>Pour connecter votre Shellfire Box \u00e0 votre TV en Ethernet, tout vos appareils doivent se trouver dans la m\u00eame pi\u00e8ce. Voici quelques \u00e9tapes \u00e0 suivre pour r\u00e9aliser le branchement tr\u00e8s facilement :<\/span><\/p>\n<ol>\n<li class=\"p1\"><span class=\"s1\">Branchez l&#8217;une des extr\u00e9mit\u00e9 du c\u00e2ble Ethernet au port LAN de votre routeur Shellfire.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Branchez l&#8217;autre extr\u00e9mit\u00e9 \u00e0 votre t\u00e9l\u00e9viseur (prise au dos de la TV).<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Sur votre t\u00e9l\u00e9commande, appuyez sur le bouton &#8220;Menu&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Choisissez l&#8217;option &#8220;Param\u00e8tres&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Allez dans les options &#8220;R\u00e9seau&#8221; puis &#8220;Param\u00e8tres R\u00e9seau&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Choisissez &#8220;Connexion par c\u00e2ble&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Lorsque cela vous est demand\u00e9, choisissez l&#8217;option &#8220;Auto&#8221; et attendez.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Une fois le param\u00e9trage termin\u00e9, il ne vous reste plus qu&#8217;a s\u00e9lectionner &#8220;Sauvegarder et se connecter&#8221;.\u00a0<\/span><\/li>\n<\/ol>\n<p class=\"p1\"><span class=\"s1\">Votre t\u00e9l\u00e9vision Sony est d\u00e9sormais connect\u00e9e \u00e0 Internet via votre routeur VPN Shellfire.\u00a0<\/span><\/p>\n<h2 class=\"p1\"><span class=\"s1\"><b>Connecter votre TV Linux au routeur Shellfire Box en WiFi<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Les utilisateurs dont le routeur internet ne se trouvent pas \u00e0 proximit\u00e9 de leur t\u00e9l\u00e9vision peuvent connecter leur Shellfire Box en WiFi.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Les mod\u00e8les suivants de t\u00e9l\u00e9visions connect\u00e9es Sony tournent sous Linux et peuvent \u00eatre connect\u00e9es en WiFi :<\/span><\/p>\n<blockquote>\n<p class=\"p5\"><span class=\"s1\"><i>KD100XD9, KD75XD9, KD65XD9, KD75XE940, KD65XE930, KD55XE930, KD75XE90, KD65XE90, KD55XE90, KD49XE90.<\/i><\/span><\/p>\n<\/blockquote>\n<p><span class=\"s1\">Si vous poss\u00e9dez l&#8217;un de ces mod\u00e8les, vous n&#8217;avez qu&#8217;a suivre la proc\u00e9dure ci-dessous pour vous connecter au routeur VPN Shellfire.<\/span><\/p>\n<ol>\n<li class=\"p1\"><span class=\"s1\">Appuyez sur le bouton &#8220;Menu&#8221; de votre t\u00e9l\u00e9commande.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Allez dans les &#8220;Param\u00e8tres&#8221;.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">S\u00e9lectionnez &#8220;R\u00e9seau&#8221;, puis &#8220;Param\u00e8tres R\u00e9seau&#8221;<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Choisissez &#8220;Connexion Sans Fil&#8221; et appuyez sur &#8220;Rechercher&#8221;.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Votre t\u00e9l\u00e9vision va automatiquement rechercher les r\u00e9seaux disponibles. Recherchez e r\u00e9seau WiFi dont le nom correspond \u00e0 celui indiqu\u00e9 en-dessous de votre Shellfire Box.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Il vous faudra saisir un mot de passe, il se trouve \u00e9galement en-dessous de votre box Shellfire. Appuyez sur &#8220;Continuer&#8221;.\u00a0<\/span><\/li>\n<\/ol>\n<p class=\"p1\"><span class=\"s1\">Votre t\u00e9l\u00e9vision Sony est d\u00e9sormais connect\u00e9e au routeur VPN Shellfire via WiFi.\u00a0<\/span><\/p>\n<h2 class=\"p1\"><span class=\"s1\"><b><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4607\" src=\"https:\/\/how-to.watch\/edirewhu\/2018\/01\/image5.jpg\" alt=\"Sony TV with BIVL\" width=\"1280\" height=\"720\" srcset=\"https:\/\/how-to.watch\/edirewhu\/2018\/01\/image5.jpg 1280w, https:\/\/how-to.watch\/edirewhu\/2018\/01\/image5-300x169.jpg 300w, https:\/\/how-to.watch\/edirewhu\/2018\/01\/image5-768x432.jpg 768w, https:\/\/how-to.watch\/edirewhu\/2018\/01\/image5-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>How to connect your<br \/>\nConnecter les t\u00e9l\u00e9visions Sony \u00e9quip\u00e9es avec BIVL au routeur Shellfire<\/b><\/span><\/h2>\n<p>Les anciens mod\u00e8les de t\u00e9l\u00e9visions Sony \u00e9taient \u00e9quip\u00e9e avec le BIVL ou\u00a0<span class=\"s1\">Bravia Internet Video Link. Sony ayant toujours eu une longueur d&#8217;avance dans la course \u00e0 l&#8217;m\u00e9lioration technologique, le BIVL a \u00e9t\u00e9 abandonn\u00e9 au profit de la VOD (Video on Demand), et ce d\u00e8s 2007. Le service \u00e9tait accessible gr\u00e2ce \u00e0 un boitier additionnel accroch\u00e9 au dos de la TV et n&#8217;\u00e9tait compatible qu&#8217;avec les tv Sony. Ce syst\u00e8me permettait aux utilisateurs d&#8217;<a href=\"https:\/\/how-to.watch\/fr\/\">acc\u00e9der \u00e0 des contenus videos<\/a>\u00a0 sur AOL, Grouper, Yahoo etc. En 2009, Netflix s&#8217;est ajout\u00e9 \u00e0 la liste.\u00a0<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4614 alignright\" src=\"https:\/\/how-to.watch\/edirewhu\/2018\/01\/image6.png\" alt=\"BIVL Shellfire Network Settup\" width=\"556\" height=\"191\" srcset=\"https:\/\/how-to.watch\/edirewhu\/2018\/01\/image6.png 556w, https:\/\/how-to.watch\/edirewhu\/2018\/01\/image6-300x103.png 300w\" sizes=\"auto, (max-width: 556px) 100vw, 556px\" \/>Les t\u00e9l\u00e9vision Sony \u00e9quip\u00e9es BIVL ne peuvent pas non plus b\u00e9n\u00e9ficier d&#8217;un VPN sous forme logicielle. Vous devrez obligatoirement passer par un routeur VPN. L\u00e0 encore, le routeur Shellfire est une solution sans d\u00e9faut : gr\u00e2ce \u00e0 diff\u00e9rents produits et solutions, vous trouverez forcement ce qui vous convient.\u00a0<\/span><\/p>\n<h2 class=\"p1\"><span class=\"s1\"><b>Connecter les t\u00e9l\u00e9visions Sony \u00e9quip\u00e9es avec BIVL au routeur Shellfire via c\u00e2ble Ethernet<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Si vous poss\u00e9dez l&#8217;un de ces mod\u00e8les de t\u00e9l\u00e9vision Sony, elle est \u00e9quip\u00e9e BIVL et peut \u00eatre connect\u00e9e en Ehernet.\u00a0<\/span><\/p>\n<blockquote>\n<p class=\"p5\"><span class=\"s1\"><i>KDL-46XBR5, KDL-46XBR6, KDL-46XBR8, KDL-46XBR9, KDL-52EX700, KDL-52EX700, KDL-52EX701, KDL-52EX701, KDL-52XBR10, KDL-52XBR2, KDL-52XBR3, KDL-55NX720, KDL-60NX801, KDL-60NX810, XBR-52HX900, XBR-52HX909, KDL-55HX729, KDL-55HX750, KDL-55HX751, KDL-55HX800, KDL-55HX820, KDL-60NX720, KDL-60NX800, KDL-48R470B, KDL-48R510C, KDL-48W580B, KDL-48W590B, KDL-50EX645, KDL-55BX520, KDL-55EX500, KDL-55EX501, KDL-55EX620, KDL-55EX621, KDL-55EX640, KDL-55EX710, KDL-55EX711, KDL-55EX720, KDL-55EX723, KDL-55HX701, KDL-55HX850, KDL-60EX500, XBR55X900A, XBR65X850A, XBR55X850A, KDL-65S990A, XBR65HX950, XBR55HX950, KD65HX950, KD55HX950, KDL55W900A, KDL-65W850A, KDL-55W802A, KDL-47W802A, KDL-32W650A, KDL-70R550A, KDL-60R550A, KDL-50R550A, KDL-70R520A, KDL-60R520A, KDL-50R450A, KDL-40R450A, KDL32R400A, KDL-46EX700, KDL-46EX701, KDL-46EX710, KDL-46EX711, KDL-46EX720, KDL-46EX723, KDL-46EX729, KDL-46HX701, , KDL-46HX729, KDL-46HX750, KDL-46HX800, KDL-46HX820, KDL-, 6HX850, KDL-46NX700, KDL-46NX711, KDL-46NX720, KDL-46NX800, KDL-46NX810, KDL-46R453A, KDL-46S2000, KDL-46S2010, KDL-46S3000, KDL-46S4100, KDL-46S504, KDL-46S5100, KDL-46SL140.<\/i><\/span><\/p>\n<\/blockquote>\n<ol>\n<li class=\"p1\"><span class=\"s1\">Branchez le c\u00e2ble Ethernet au port LAN du routeur Shellfire, et l&#8217;autre extr\u00e9mit\u00e9 au dos de votre t\u00e9l\u00e9vision Sony.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Appuyez sur le bouton &#8220;Menu&#8221; de votre t\u00e9l\u00e9commande.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Cherchez les &#8220;Param\u00e8tres&#8221;.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Choisissez le menu &#8220;R\u00e9seau&#8221;, puis appuyez sur &#8220;Param\u00e8tres R\u00e9seau&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">A partir de l\u00e0, vous avez le choix entre deux options\u00a0 : &#8220;Configuration automatique&#8221; ou &#8220;Configuration personnalis\u00e9e&#8221;.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Nous vous recommandons d&#8217;opter pour la configuration automatique.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Si vous optez pour l&#8217;option &#8220;Configuration Personnalis\u00e9e&#8221;, vous devrez saisir manuellement les informations concernant le proxy et l&#8217;adresse IP. Ce n&#8217;est pas une option recommand\u00e9e pour les novices.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Une fois la configuration termin\u00e9e, vous n&#8217;avez plus qu&#8217;a appuyez sur &#8220;Sauvegarder et se connecter&#8221;.\u00a0<\/span><\/li>\n<\/ol>\n<p class=\"p1\"><span class=\"s1\">Votre t\u00e9l\u00e9vision Sony est d\u00e9sormais connect\u00e9e \u00e0 Internet en ethernet via votre routeur VPN Shellfire.<\/span><\/p>\n<h2 class=\"p1\"><span class=\"s1\"><b>Connecter les t\u00e9l\u00e9visions Sony \u00e9quip\u00e9es avec BIVL au routeur Shellfire via WiFi<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Si vous poss\u00e9dez l&#8217;un de ces mod\u00e8les de t\u00e9l\u00e9vision Sony, elle est \u00e9quip\u00e9e BIVL et peut \u00eatre connect\u00e9e en WiFi.<\/span><\/p>\n<blockquote>\n<p class=\"p5\"><span class=\"s1\"><i>KDL55W900A, KDL-65W850A, KDL-55W802A, KDL-47W802A, KDL-32W650A, KDL-70R550A, KDL-60R550A, KDL-50R550A, KDL-70R520A, KDL-60R520A, KDL-50R450A, KDL-40R450A, KDL-32R400A, KDL-46EX700, KDL-46EX701, KDL-46EX710, KDL-46EX711, KDL-46EX720, KDL-46EX723, KDL-46EX729, KDL-46HX701, KDL-46HX729, KDL-46HX750, KDL-46HX800, KDL-46HX820, KDL-46HX850, KDL6NX700, KDL-46NX711, KDL-46NX720, KDL-46NX800, KDL-46NX810, KDL-46R453A, KDL-46S2000, KDL-46S2010, KDL-46S3000, KDL-46S4100, KDL-46S504, KDL-46S5100, KDL-46SL140, KDL-46V2500, PDM-4200, PDM-4210, PDM-5000, KZ-32TS1, PDM-5010, PDM-5510, PDM-6110, KDE-37XS955, KDE2XBR950, KDE-42XS955, KDE-50XBR950, KDE-50XS955, KDE-55XBR950, KDE-61XBR950, KE-XBR900, KE-42XS910, KE-50XBR900, KE-50XS910, KDL-V26XBR1, KDL-V32XBR1, KDL-V32XBR2,<\/i><\/span><span class=\"s1\"><i>KDL-V40XBR1, KE-32TS2, KE-32TS2U, KE-37XS910, KE-42M1m KE-42TS2U, KDL-46W5150, KDL-46WL135, KDL-46WL140, KDL-52W3000, KDL-52W4100, KDL-70X830B, , KDL-70XBR3, KDL-70XBR7, XEL-1, KDL-, 6V3000, KDL-46V4100, KDL-46V5100, KDL-46VE5, KDL-46W3000, KDL-46W4100, KDL-46W4150, KDL-46W5100, KDL-46Z4100, KDL-46Z5100, KDL-52NX800, KDL-52S4100, KDL-52S5100, KDL-52V4100. KDL-52V5100, KDL-52VE5, KDL-52VL150, KDL-52W5100, KDL-52W5150l, KDL-52WL130, KDL-52WL135, KDL-52WL140, KDL-52XBR4, KDL-52XBR5, KDL-52XBR6, KDL-52XBR7, KDL-52XBR9, KDL-52Z5100, KDL-55NX810, KDL-55V5100, KDL-55XBR8, KDL-46VL130, KDL-46VL150, KDL-55EX640, KDL-55EX710, KDL-55EX711, KDL-55EX720, KDL-55EX723, KDL-55HX701, KDL-55HX850, KDL-60EX500, KDL-60EX645, KDL-60EX700, KDL-60EX701, KDL-60EX720, KDL-60EX723, KDL-65HX729, KDL-47W802A, KDL-50R450A, KDL-46XBR6, KDL-46XBR8, KDL-46XBR9, KDL-52EX700, KDL-52EX700, KDL-52EX701, KDL-52EX701, KDL-52XBR10, KDL-52XBR2, KDL-52XBR3, KDL-55NX720, KDL-60NX801, KDL-60NX810, XBR-52HX900, XBR-52HX909, KDL-55HX729, KDL-55HX750, KDL-55HX751, KDL-55HX800, KDL-55HX820, KDL-60NX720, KDL-60NX800, KDL-48R470B, KDL-48R510C, KDL-48W580B, KDL-48W590B, KDL-50EX645, KDL-55BX520.<\/i><\/span><\/p>\n<\/blockquote>\n<p><span class=\"s1\">Suivez ces quelques \u00e9tapes pour connecter votre TV Sony BIVL au routeur Shellfire Box en WiFi :<\/span><\/p>\n<ol>\n<li class=\"p1\"><span class=\"s1\">Appuyez sur le bouton &#8220;Menu&#8221; de votre t\u00e9l\u00e9commande.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Choisissez les &#8220;Param\u00e8tres R\u00e9seaux&#8221;, puis &#8220;Configuration sans Fil&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Cliquez sur &#8220;Rechercher&#8221; dans le menu\u00a0 &#8220;Configuration Sans Fil&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Vous obtenez une liste des r\u00e9seaux disponibles.<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Recherchez celui dont le nom correspond \u00e0 l&#8217;\u00e9tiquette plac\u00e9e sous votre routeur Shellfire Box.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Un mot de passe va vous \u00eatre demand\u00e9. Vous le trouverez en dessous de votre routeur Shellfire. Cliquez sur &#8220;Continuer&#8221;.\u00a0 Vous n&#8217;avez plus qu&#8217;a entrer votre mot de passe securis\u00e9, via la t\u00e9l\u00e9commande et le clavier affich\u00e9 \u00e0 l&#8217;\u00e9cran.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Lorsque cela vous est demand\u00e9, choisissez l&#8217;option &#8220;Auto&#8221; \u00e0 l&#8217;\u00e9cran &#8220;Adresse IP du Serveur Proxy&#8221;.\u00a0<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">Enfin, cliquez sur &#8220;Sauvegarder et se connecter&#8221;. Confirmez que la connexion est bien r\u00e9ussie et appuyez sur &#8220;Ok'&#8221;.\u00a0<\/span><\/li>\n<\/ol>\n<p class=\"p1\"><span class=\"s1\">Votre t\u00e9l\u00e9vision Sony est d\u00e9sormais connect\u00e9e \u00e0 Internet en WiFi via votre routeur VPN Shellfire.<\/span><\/p>\n<h2 class=\"p4\"><span class=\"s1\"><b>En conclusion<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Sony, sans l&#8217;ombre d&#8217;un doute, s&#8217;est bel et bien impos\u00e9 comme un acteur pr\u00e9pond\u00e9rant de l&#8217;innovation technologique. Malgr\u00e9 tout, il est probable que l&#8217;Internet reste toujours, si ce n&#8217;est plus, limit\u00e9 par la censure et le g\u00e9o-blocking.\u00a0 Fort heureusement, il est toujours possible de contourner le g\u00e9o-blocking sans pour autant y sacrifier qualit\u00e9 et facilit\u00e9 d&#8217;utilisation. Shellfire offre diff\u00e9rentes solutions, que ce soit mat\u00e9riel ou logiciel, pour pouvoir tirer tout le b\u00e9n\u00e9fice d&#8217;un VPN et l&#8217;utiliser pour connecter votre t\u00e9l\u00e9vision connect\u00e9e Sony. Si vous avez un soucis avec la censure ou le g\u00e9o-blocking, essayez donc <a href=\"https:\/\/www.shellfire.fr\">Shellfire<\/a>. Vous b\u00e9n\u00e9ficiez pour tous les produits d&#8217;une offre satisfait ou rembours\u00e9 de 14 jours : vous ne prenez donc aucun risque \u00e0 essayer !<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au cours des ann\u00e9es, Sony s&#8217;est impos\u00e9 comme le leader de la technologie t\u00e9l\u00e9visuelle. Et aujourd&#8217;hui encore plus que jamais, les t\u00e9l\u00e9visions connect\u00e9es Sony offrent une polyvalence et un plaisir \u00e0 l&#8217;utilisation in\u00e9gal\u00e9s pour l&#8217;utilisateur. Sony parvient \u00e0 repousser de mani\u00e8re constante les fronti\u00e8res de la technologie. De la HD tr\u00e8s haute qualit\u00e9 et la &#8230;<\/p>\n","protected":false},"author":8,"featured_media":4623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291],"tags":[1121,1122,1034,385,331,1120,1123,1118,1119,288,293],"class_list":["post-4687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reseau-prive-virtuel","tag-routeur-shellfire","tag-routeur-shellfire-box","tag-shellfire-fr","tag-shellfire-box-fr","tag-smart-tv-fr","tag-sony-fr","tag-tv-android","tag-tv-connectee-sony","tag-tv-sony","tag-vpn-fr-2","tag-vpn-shellfire-fr"],"yoast_head":"\n<title>D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box, quelles sont les t\u00e9l\u00e9visions qui sont ou pas support\u00e9es et des instructions pas \u00e0 pas en ethernet et en wifi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box, quelles sont les t\u00e9l\u00e9visions qui sont ou pas support\u00e9es et des instructions pas \u00e0 pas en ethernet et en wifi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/\" \/>\n<meta property=\"og:site_name\" content=\"How To Watch\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-18T20:16:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/how-to.watch\/edirewhu\/2018\/01\/Sony-Smart-TV.png\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"583\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Amelie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amelie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/\"},\"author\":{\"name\":\"Amelie\",\"@id\":\"https:\\\/\\\/how-to.watch\\\/de\\\/#\\\/schema\\\/person\\\/6c29961d662759556cf03ca299992ac5\"},\"headline\":\"Connecter votre TV Connect\u00e9e Sony \u00e0 un VPN\",\"datePublished\":\"2018-01-18T20:16:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/\"},\"wordCount\":3523,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/how-to.watch\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/how-to.watch\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Sony-Smart-TV.png\",\"keywords\":[\"Routeur Shellfire\",\"Routeur Shellfire Box\",\"Shellfire\",\"Shellfire Box\",\"Smart TV\",\"Sony\",\"TV Android\",\"TV Connect\u00e9e Sony\",\"TV Sony\",\"VPN\",\"VPN Shellfire\"],\"articleSection\":[\"R\u00e9seau Priv\u00e9 Virtuel\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/\",\"url\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/\",\"name\":\"D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/how-to.watch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/how-to.watch\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Sony-Smart-TV.png\",\"datePublished\":\"2018-01-18T20:16:28+00:00\",\"description\":\"D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box, quelles sont les t\u00e9l\u00e9visions qui sont ou pas support\u00e9es et des instructions pas \u00e0 pas en ethernet et en wifi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/how-to.watch\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Sony-Smart-TV.png\",\"contentUrl\":\"https:\\\/\\\/how-to.watch\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Sony-Smart-TV.png\",\"width\":960,\"height\":583},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/connecter-tv-sony-vpn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/how-to.watch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Connecter votre TV Connect\u00e9e Sony \u00e0 un VPN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/how-to.watch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/how-to.watch\\\/de\\\/\",\"name\":\"How To Watch\",\"description\":\"The easy way to unblock your favourite streaming sites\",\"publisher\":{\"@id\":\"https:\\\/\\\/how-to.watch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/how-to.watch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/how-to.watch\\\/de\\\/#organization\",\"name\":\"how-to.watch\",\"url\":\"https:\\\/\\\/how-to.watch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/how-to.watch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/how-to.watch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/blogo.png\",\"contentUrl\":\"https:\\\/\\\/how-to.watch\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/blogo.png\",\"width\":4002,\"height\":1015,\"caption\":\"how-to.watch\"},\"image\":{\"@id\":\"https:\\\/\\\/how-to.watch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/how-to.watch\\\/de\\\/#\\\/schema\\\/person\\\/6c29961d662759556cf03ca299992ac5\",\"name\":\"Amelie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e51e91a222ad6bfb29ffc2f2fb894d54f4cf74205516409220fee66cde183e1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e51e91a222ad6bfb29ffc2f2fb894d54f4cf74205516409220fee66cde183e1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e51e91a222ad6bfb29ffc2f2fb894d54f4cf74205516409220fee66cde183e1c?s=96&d=mm&r=g\",\"caption\":\"Amelie\"}}]}<\/script>\n","yoast_head_json":{"title":"D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box","description":"D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box, quelles sont les t\u00e9l\u00e9visions qui sont ou pas support\u00e9es et des instructions pas \u00e0 pas en ethernet et en wifi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box","og_description":"D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box, quelles sont les t\u00e9l\u00e9visions qui sont ou pas support\u00e9es et des instructions pas \u00e0 pas en ethernet et en wifi.","og_url":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/","og_site_name":"How To Watch","article_published_time":"2018-01-18T20:16:28+00:00","og_image":[{"width":960,"height":583,"url":"https:\/\/how-to.watch\/edirewhu\/2018\/01\/Sony-Smart-TV.png","type":"image\/png"}],"author":"Amelie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Amelie","Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/#article","isPartOf":{"@id":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/"},"author":{"name":"Amelie","@id":"https:\/\/how-to.watch\/de\/#\/schema\/person\/6c29961d662759556cf03ca299992ac5"},"headline":"Connecter votre TV Connect\u00e9e Sony \u00e0 un VPN","datePublished":"2018-01-18T20:16:28+00:00","mainEntityOfPage":{"@id":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/"},"wordCount":3523,"commentCount":0,"publisher":{"@id":"https:\/\/how-to.watch\/de\/#organization"},"image":{"@id":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/#primaryimage"},"thumbnailUrl":"https:\/\/how-to.watch\/edirewhu\/2018\/01\/Sony-Smart-TV.png","keywords":["Routeur Shellfire","Routeur Shellfire Box","Shellfire","Shellfire Box","Smart TV","Sony","TV Android","TV Connect\u00e9e Sony","TV Sony","VPN","VPN Shellfire"],"articleSection":["R\u00e9seau Priv\u00e9 Virtuel"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/","url":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/","name":"D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box","isPartOf":{"@id":"https:\/\/how-to.watch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/#primaryimage"},"image":{"@id":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/#primaryimage"},"thumbnailUrl":"https:\/\/how-to.watch\/edirewhu\/2018\/01\/Sony-Smart-TV.png","datePublished":"2018-01-18T20:16:28+00:00","description":"D\u00e9couvrez comment connecter votre TV connect\u00e9e Sony au routeur Shellfire Box, quelles sont les t\u00e9l\u00e9visions qui sont ou pas support\u00e9es et des instructions pas \u00e0 pas en ethernet et en wifi.","breadcrumb":{"@id":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/#primaryimage","url":"https:\/\/how-to.watch\/edirewhu\/2018\/01\/Sony-Smart-TV.png","contentUrl":"https:\/\/how-to.watch\/edirewhu\/2018\/01\/Sony-Smart-TV.png","width":960,"height":583},{"@type":"BreadcrumbList","@id":"https:\/\/how-to.watch\/fr\/connecter-tv-sony-vpn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/how-to.watch\/fr\/"},{"@type":"ListItem","position":2,"name":"Connecter votre TV Connect\u00e9e Sony \u00e0 un VPN"}]},{"@type":"WebSite","@id":"https:\/\/how-to.watch\/de\/#website","url":"https:\/\/how-to.watch\/de\/","name":"How To Watch","description":"The easy way to unblock your favourite streaming sites","publisher":{"@id":"https:\/\/how-to.watch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/how-to.watch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/how-to.watch\/de\/#organization","name":"how-to.watch","url":"https:\/\/how-to.watch\/de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/how-to.watch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/how-to.watch\/edirewhu\/2017\/11\/blogo.png","contentUrl":"https:\/\/how-to.watch\/edirewhu\/2017\/11\/blogo.png","width":4002,"height":1015,"caption":"how-to.watch"},"image":{"@id":"https:\/\/how-to.watch\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/how-to.watch\/de\/#\/schema\/person\/6c29961d662759556cf03ca299992ac5","name":"Amelie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e51e91a222ad6bfb29ffc2f2fb894d54f4cf74205516409220fee66cde183e1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e51e91a222ad6bfb29ffc2f2fb894d54f4cf74205516409220fee66cde183e1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e51e91a222ad6bfb29ffc2f2fb894d54f4cf74205516409220fee66cde183e1c?s=96&d=mm&r=g","caption":"Amelie"}}]}},"_links":{"self":[{"href":"https:\/\/how-to.watch\/fr\/wp-json\/wp\/v2\/posts\/4687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/how-to.watch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/how-to.watch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/how-to.watch\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/how-to.watch\/fr\/wp-json\/wp\/v2\/comments?post=4687"}],"version-history":[{"count":0,"href":"https:\/\/how-to.watch\/fr\/wp-json\/wp\/v2\/posts\/4687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/how-to.watch\/fr\/wp-json\/wp\/v2\/media\/4623"}],"wp:attachment":[{"href":"https:\/\/how-to.watch\/fr\/wp-json\/wp\/v2\/media?parent=4687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/how-to.watch\/fr\/wp-json\/wp\/v2\/categories?post=4687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/how-to.watch\/fr\/wp-json\/wp\/v2\/tags?post=4687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}